{"id":15,"count":0,"description":"","link":"https:\/\/executive-resumes.com.au\/store\/product-category\/optional-extras\/","name":"Optional Extras","slug":"optional-extras","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Optional Extras - Executive Resumes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/executive-resumes.com.au\/store\/product-category\/optional-extras\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Optional Extras - Executive Resumes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/executive-resumes.com.au\/store\/product-category\/optional-extras\/\" \/>\n<meta property=\"og:site_name\" content=\"Executive Resumes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/executive-resumes.com.au\\\/store\\\/product-category\\\/optional-extras\\\/\",\"url\":\"https:\\\/\\\/executive-resumes.com.au\\\/store\\\/product-category\\\/optional-extras\\\/\",\"name\":\"Optional Extras - Executive Resumes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/executive-resumes.com.au\\\/store\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/executive-resumes.com.au\\\/store\\\/product-category\\\/optional-extras\\\/#breadcrumb\"},\"inLanguage\":\"en-AU\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/executive-resumes.com.au\\\/store\\\/product-category\\\/optional-extras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/executive-resumes.com.au\\\/store\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Optional Extras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/executive-resumes.com.au\\\/store\\\/#website\",\"url\":\"https:\\\/\\\/executive-resumes.com.au\\\/store\\\/\",\"name\":\"Executive Resumes\",\"description\":\"Packages and Prices\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/executive-resumes.com.au\\\/store\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-AU\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Optional Extras - Executive Resumes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/executive-resumes.com.au\/store\/product-category\/optional-extras\/","og_locale":"en_US","og_type":"article","og_title":"Optional Extras - Executive Resumes","og_url":"https:\/\/executive-resumes.com.au\/store\/product-category\/optional-extras\/","og_site_name":"Executive Resumes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/executive-resumes.com.au\/store\/product-category\/optional-extras\/","url":"https:\/\/executive-resumes.com.au\/store\/product-category\/optional-extras\/","name":"Optional Extras - Executive Resumes","isPartOf":{"@id":"https:\/\/executive-resumes.com.au\/store\/#website"},"breadcrumb":{"@id":"https:\/\/executive-resumes.com.au\/store\/product-category\/optional-extras\/#breadcrumb"},"inLanguage":"en-AU"},{"@type":"BreadcrumbList","@id":"https:\/\/executive-resumes.com.au\/store\/product-category\/optional-extras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/executive-resumes.com.au\/store\/"},{"@type":"ListItem","position":2,"name":"Optional Extras"}]},{"@type":"WebSite","@id":"https:\/\/executive-resumes.com.au\/store\/#website","url":"https:\/\/executive-resumes.com.au\/store\/","name":"Executive Resumes","description":"Packages and Prices","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/executive-resumes.com.au\/store\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-AU"}]}},"_links":{"self":[{"href":"https:\/\/executive-resumes.com.au\/store\/wp-json\/wp\/v2\/product_cat\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/executive-resumes.com.au\/store\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/executive-resumes.com.au\/store\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/executive-resumes.com.au\/store\/wp-json\/wp\/v2\/product?product_cat=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}